{"id":27,"count":9,"description":"","link":"https:\/\/www.lalouver.com\/journal\/tag\/museum","name":"museum","slug":"museum","taxonomy":"post_tag","meta":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>museum Archives - L.A. Louver - Journal<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.lalouver.com\/journal\/tag\/museum\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"museum Archives - L.A. Louver - Journal\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.lalouver.com\/journal\/tag\/museum\" \/>\r\n<meta property=\"og:site_name\" content=\"L.A. Louver - Journal\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"CollectionPage\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/tag\\\/museum\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/tag\\\/museum\",\"name\":\"museum Archives - L.A. Louver - Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/tag\\\/museum#breadcrumb\"},\"inLanguage\":\"en-US\"},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/tag\\\/museum#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"museum\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\",\"name\":\"L.A. Louver - Journal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"museum Archives - L.A. Louver - Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lalouver.com\/journal\/tag\/museum","og_locale":"en_US","og_type":"article","og_title":"museum Archives - L.A. Louver - Journal","og_url":"https:\/\/www.lalouver.com\/journal\/tag\/museum","og_site_name":"L.A. Louver - Journal","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"CollectionPage","@id":"https:\/\/www.lalouver.com\/journal\/tag\/museum","url":"https:\/\/www.lalouver.com\/journal\/tag\/museum","name":"museum Archives - L.A. Louver - Journal","isPartOf":{"@id":"https:\/\/www.lalouver.com\/journal\/#website"},"breadcrumb":{"@id":"https:\/\/www.lalouver.com\/journal\/tag\/museum#breadcrumb"},"inLanguage":"en-US"},{"@type":"BreadcrumbList","@id":"https:\/\/www.lalouver.com\/journal\/tag\/museum#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lalouver.com\/journal\/"},{"@type":"ListItem","position":2,"name":"museum"}]},{"@type":"WebSite","@id":"https:\/\/www.lalouver.com\/journal\/#website","url":"https:\/\/www.lalouver.com\/journal\/","name":"L.A. Louver - Journal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lalouver.com\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/tags\/27","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/tags"}],"about":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/taxonomies\/post_tag"}],"wp:post_type":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts?tags=27"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}