{"id":732,"date":"2015-06-17T01:15:22","date_gmt":"2015-06-17T01:15:22","guid":{"rendered":"https:\/\/www.lalouver.com\/journal\/index.php\/2015\/06\/17\/la-louvers-2014-exhibition-of-photographs-and\/"},"modified":"2025-09-05T14:54:16","modified_gmt":"2025-09-05T14:54:16","slug":"la-louvers-2014-exhibition-of-photographs-and","status":"publish","type":"post","link":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and","title":{"rendered":"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine"},"content":{"rendered":"\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a57fada9a09f&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-3 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57fada9d906&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57fada9d906\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1285\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"733\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko1_1280.jpg\" alt=\"\" class=\"wp-image-733\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko1_1280.jpg 1280w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko1_1280-300x300.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko1_1280-1020x1024.jpg 1020w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko1_1280-150x150.jpg 150w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko1_1280-768x771.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57fada9e167&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57fada9e167\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1282\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"734\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko3_1280.jpg\" alt=\"\" class=\"wp-image-734\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko3_1280.jpg 1280w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko3_1280-300x300.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko3_1280-1022x1024.jpg 1022w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko3_1280-150x150.jpg 150w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko3_1280-768x769.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57fada9e930&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57fada9e930\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1277\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"735\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko2_1280.jpg\" alt=\"\" class=\"wp-image-735\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko2_1280.jpg 1280w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko2_1280-300x300.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko2_1280-1024x1022.jpg 1024w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko2_1280-150x150.jpg 150w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko2_1280-768x766.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57fada9f0f3&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57fada9f0f3\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1280\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"736\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg\" alt=\"\" class=\"wp-image-736\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg 1280w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280-300x300.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280-1024x1024.jpg 1024w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280-150x150.jpg 150w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280-768x768.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57fada9fa86&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57fada9fa86\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1280\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"737\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko5_1280.jpg\" alt=\"\" class=\"wp-image-737\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko5_1280.jpg 1280w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko5_1280-300x300.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko5_1280-1024x1024.jpg 1024w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko5_1280-150x150.jpg 150w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko5_1280-768x768.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57fadaa0233&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57fadaa0233\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1280\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"738\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko6_1280.jpg\" alt=\"\" class=\"wp-image-738\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko6_1280.jpg 1280w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko6_1280-300x300.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko6_1280-1024x1024.jpg 1024w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko6_1280-150x150.jpg 150w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko6_1280-768x768.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57fadaa0965&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57fadaa0965\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1280\" height=\"1281\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"739\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko7_1280.jpg\" alt=\"\" class=\"wp-image-739\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko7_1280.jpg 1280w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko7_1280-300x300.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko7_1280-1024x1024.jpg 1024w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko7_1280-150x150.jpg 150w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko7_1280-768x769.jpg 768w\" sizes=\"auto, (max-width: 1280px) 100vw, 1280px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">L.A. Louver\u2019s 2014 exhibition of photographs and drawings by <a href=\"http:\/\/www.roguewaveprojects.com\/html\/chen-man.html\">Chen Man<\/a> was covered on the Chinese publication <i>Gallery Magazine<\/i>. Recognized as one of China\u2019s preeminent contemporary photographers, Chen Man bridges traditional and contemporary themes in her portrayals. Her bold compositions are often commentary on Chinese culture, but are also highly personal expressions.&nbsp;<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u201c\u2019Chen Man: East-West\u2019 brings together so much more than two halves of the glove and two visual media,\u201d writes David Pagel in <i>Gallery Magazine<\/i>,&nbsp;\u201cSex and Power entwine in Chen Man\u2019s stunning photographs.\u201d<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.roguewaveprojects.com\/html\/chen-man.html\">Click here<\/a> to see more images from Chen Man\u2019s exhibition.&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>L.A. Louver\u2019s 2014 exhibition of photographs and drawings by Chen Man was covered on the Chinese publication Gallery Magazine. Recognized as one of China\u2019s preeminent contemporary photographers, Chen Man bridges traditional and contemporary themes in her portrayals. Her bold compositions are often commentary on Chinese culture, but are also highly personal expressions.&nbsp; \u201c\u2019Chen Man: East-West\u2019 [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":736,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[1],"tags":[254,256,15,274,79],"class_list":["post-732","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-uncategorized","tag-chen-man","tag-china","tag-l-a-louver","tag-paintings","tag-photography","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine - L.A. Louver - Journal<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine - L.A. Louver - Journal\" \/>\r\n<meta property=\"og:description\" content=\"L.A. Louver\u2019s 2014 exhibition of photographs and drawings by Chen Man was covered on the Chinese publication Gallery Magazine. Recognized as one of China\u2019s preeminent contemporary photographers, Chen Man bridges traditional and contemporary themes in her portrayals. Her bold compositions are often commentary on Chinese culture, but are also highly personal expressions.&nbsp; \u201c\u2019Chen Man: East-West\u2019 [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and\" \/>\r\n<meta property=\"og:site_name\" content=\"L.A. Louver - Journal\" \/>\r\n<meta property=\"article:published_time\" content=\"2015-06-17T01:15:22+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-09-05T14:54:16+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1280\" \/>\r\n\t<meta property=\"og:image:height\" content=\"1280\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"L.A. Louver\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"L.A. Louver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and\"},\"author\":{\"name\":\"L.A. Louver\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\"},\"headline\":\"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine\",\"datePublished\":\"2015-06-17T01:15:22+00:00\",\"dateModified\":\"2025-09-05T14:54:16+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and\"},\"wordCount\":115,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg\",\"keywords\":[\"Chen Man\",\"China\",\"l.a. louver\",\"paintings\",\"photography\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and\",\"name\":\"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine - L.A. Louver - Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg\",\"datePublished\":\"2015-06-17T01:15:22+00:00\",\"dateModified\":\"2025-09-05T14:54:16+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#primaryimage\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2015\\\/06\\\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg\",\"width\":1280,\"height\":1280},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/la-louvers-2014-exhibition-of-photographs-and#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\",\"name\":\"L.A. Louver - Journal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\",\"name\":\"L.A. Louver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"caption\":\"L.A. Louver\"},\"sameAs\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\"],\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/author\\\/50percentopacity\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine - L.A. Louver - Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and","og_locale":"en_US","og_type":"article","og_title":"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine - L.A. Louver - Journal","og_description":"L.A. Louver\u2019s 2014 exhibition of photographs and drawings by Chen Man was covered on the Chinese publication Gallery Magazine. Recognized as one of China\u2019s preeminent contemporary photographers, Chen Man bridges traditional and contemporary themes in her portrayals. Her bold compositions are often commentary on Chinese culture, but are also highly personal expressions.&nbsp; \u201c\u2019Chen Man: East-West\u2019 [&hellip;]","og_url":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and","og_site_name":"L.A. Louver - Journal","article_published_time":"2015-06-17T01:15:22+00:00","article_modified_time":"2025-09-05T14:54:16+00:00","og_image":[{"width":1280,"height":1280,"url":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg","type":"image\/jpeg"}],"author":"L.A. Louver","twitter_card":"summary_large_image","twitter_misc":{"Written by":"L.A. Louver","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#article","isPartOf":{"@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and"},"author":{"name":"L.A. Louver","@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158"},"headline":"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine","datePublished":"2015-06-17T01:15:22+00:00","dateModified":"2025-09-05T14:54:16+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and"},"wordCount":115,"commentCount":0,"image":{"@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#primaryimage"},"thumbnailUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg","keywords":["Chen Man","China","l.a. louver","paintings","photography"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and","url":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and","name":"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine - L.A. Louver - Journal","isPartOf":{"@id":"https:\/\/www.lalouver.com\/journal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#primaryimage"},"image":{"@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#primaryimage"},"thumbnailUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg","datePublished":"2015-06-17T01:15:22+00:00","dateModified":"2025-09-05T14:54:16+00:00","author":{"@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158"},"breadcrumb":{"@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#primaryimage","url":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg","contentUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2015\/06\/tumblr_nq2e5mFjVj1r7s5hko4_1280.jpg","width":1280,"height":1280},{"@type":"BreadcrumbList","@id":"https:\/\/www.lalouver.com\/journal\/la-louvers-2014-exhibition-of-photographs-and#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lalouver.com\/journal\/"},{"@type":"ListItem","position":2,"name":"Our exhibition by Chen Man was covered on the Chinese publication Gallery Magazine"}]},{"@type":"WebSite","@id":"https:\/\/www.lalouver.com\/journal\/#website","url":"https:\/\/www.lalouver.com\/journal\/","name":"L.A. Louver - Journal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lalouver.com\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158","name":"L.A. Louver","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","caption":"L.A. Louver"},"sameAs":["https:\/\/www.lalouver.com\/journal"],"url":"https:\/\/www.lalouver.com\/journal\/author\/50percentopacity"}]}},"_links":{"self":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/732","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/comments?post=732"}],"version-history":[{"count":3,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/732\/revisions"}],"predecessor-version":[{"id":5066,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/732\/revisions\/5066"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/media\/736"}],"wp:attachment":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/media?parent=732"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/categories?post=732"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/tags?post=732"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}