{"id":1459,"date":"2013-11-29T18:01:13","date_gmt":"2013-11-29T18:01:13","guid":{"rendered":"https:\/\/www.lalouver.com\/journal\/index.php\/2013\/11\/29\/looking-for-post-thanksgiving-plans-the-gallery\/"},"modified":"2025-09-06T16:49:23","modified_gmt":"2025-09-06T16:49:23","slug":"looking-for-post-thanksgiving-plans-the-gallery","status":"publish","type":"post","link":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery","title":{"rendered":"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place"},"content":{"rendered":"\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a57f9bf31bf5&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-3 wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf35668&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf35668\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1080\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1460\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko1_1280.jpg\" alt=\"\" class=\"wp-image-1460\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko1_1280.jpg 720w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko1_1280-200x300.jpg 200w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko1_1280-683x1024.jpg 683w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf35ea0&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf35ea0\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1080\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1461\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko2_1280.jpg\" alt=\"\" class=\"wp-image-1461\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko2_1280.jpg 720w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko2_1280-200x300.jpg 200w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko2_1280-683x1024.jpg 683w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf368a7&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf368a7\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1080\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1468\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko9_1280.jpg\" alt=\"\" class=\"wp-image-1468\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko9_1280.jpg 720w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko9_1280-200x300.jpg 200w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko9_1280-683x1024.jpg 683w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf37069&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf37069\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"960\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1463\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko4_1280.jpg\" alt=\"\" class=\"wp-image-1463\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko4_1280.jpg 720w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko4_1280-225x300.jpg 225w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf377e3&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf377e3\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1080\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1464\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko6_1280.jpg\" alt=\"\" class=\"wp-image-1464\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko6_1280.jpg 720w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko6_1280-200x300.jpg 200w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko6_1280-683x1024.jpg 683w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf37f52&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf37f52\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"720\" height=\"1080\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1469\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko10_1280.jpg\" alt=\"\" class=\"wp-image-1469\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko10_1280.jpg 720w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko10_1280-200x300.jpg 200w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko10_1280-683x1024.jpg 683w\" sizes=\"auto, (max-width: 720px) 100vw, 720px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf38718&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf38718\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1465\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko5_1280.jpg\" alt=\"\" class=\"wp-image-1465\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko5_1280.jpg 960w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko5_1280-300x225.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko5_1280-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf38e8f&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf38e8f\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"1080\" height=\"720\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1462\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg\" alt=\"\" class=\"wp-image-1462\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg 1080w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280-300x200.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280-1024x683.jpg 1024w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280-768x512.jpg 768w\" sizes=\"auto, (max-width: 1080px) 100vw, 1080px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf395f2&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf395f2\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1467\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko8_1280.jpg\" alt=\"\" class=\"wp-image-1467\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko8_1280.jpg 960w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko8_1280-300x225.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko8_1280-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n\n\n\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57f9bf39ead&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57f9bf39ead\" class=\"wp-block-image size-full wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"960\" height=\"720\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1466\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko7_1280.jpg\" alt=\"\" class=\"wp-image-1466\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko7_1280.jpg 960w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko7_1280-300x225.jpg 300w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko7_1280-768x576.jpg 768w\" sizes=\"auto, (max-width: 960px) 100vw, 960px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">Looking for post-Thanksgiving plans? The gallery is open to the public both Friday (11\/29) and Saturday (11\/30), so come by and see our Joel Shapiro exhibition, which includes freestanding sculptures and a spectacular installation of suspended work.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">To give you an idea of how the installation came together, we\u2019ve included a few snaps of Joel and crew skillfully situating the brilliant wooden forms in place.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><a href=\"http:\/\/www.lalouver.com\/html\/exhibition.cfm?tExhibition_id=998\">For more works in the exhibition, visit our website.<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">On view through January 11th<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Looking for post-Thanksgiving plans? The gallery is open to the public both Friday (11\/29) and Saturday (11\/30), so come by and see our Joel Shapiro exhibition, which includes freestanding sculptures and a spectacular installation of suspended work. To give you an idea of how the installation came together, we\u2019ve included a few snaps of Joel [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1462,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[1],"tags":[44,459,15,903,438],"class_list":["post-1459","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-uncategorized","tag-installation","tag-joel-shapiro","tag-l-a-louver","tag-suspended-work","tag-wood","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place - L.A. Louver - Journal<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place - L.A. Louver - Journal\" \/>\r\n<meta property=\"og:description\" content=\"Looking for post-Thanksgiving plans? The gallery is open to the public both Friday (11\/29) and Saturday (11\/30), so come by and see our Joel Shapiro exhibition, which includes freestanding sculptures and a spectacular installation of suspended work. To give you an idea of how the installation came together, we\u2019ve included a few snaps of Joel [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery\" \/>\r\n<meta property=\"og:site_name\" content=\"L.A. Louver - Journal\" \/>\r\n<meta property=\"article:published_time\" content=\"2013-11-29T18:01:13+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-09-06T16:49:23+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"1080\" \/>\r\n\t<meta property=\"og:image:height\" content=\"720\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"L.A. Louver\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"L.A. Louver\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery\"},\"author\":{\"name\":\"L.A. Louver\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\"},\"headline\":\"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place\",\"datePublished\":\"2013-11-29T18:01:13+00:00\",\"dateModified\":\"2025-09-06T16:49:23+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery\"},\"wordCount\":93,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg\",\"keywords\":[\"installation\",\"Joel Shapiro\",\"l.a. louver\",\"suspended work\",\"wood\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery\",\"name\":\"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place - L.A. Louver - Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg\",\"datePublished\":\"2013-11-29T18:01:13+00:00\",\"dateModified\":\"2025-09-06T16:49:23+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2013\\\/11\\\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg\",\"width\":1080,\"height\":720},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/looking-for-post-thanksgiving-plans-the-gallery#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\",\"name\":\"L.A. Louver - Journal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\",\"name\":\"L.A. Louver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"caption\":\"L.A. Louver\"},\"sameAs\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\"],\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/author\\\/50percentopacity\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place - L.A. Louver - Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery","og_locale":"en_US","og_type":"article","og_title":"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place - L.A. Louver - Journal","og_description":"Looking for post-Thanksgiving plans? The gallery is open to the public both Friday (11\/29) and Saturday (11\/30), so come by and see our Joel Shapiro exhibition, which includes freestanding sculptures and a spectacular installation of suspended work. To give you an idea of how the installation came together, we\u2019ve included a few snaps of Joel [&hellip;]","og_url":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery","og_site_name":"L.A. Louver - Journal","article_published_time":"2013-11-29T18:01:13+00:00","article_modified_time":"2025-09-06T16:49:23+00:00","og_image":[{"width":1080,"height":720,"url":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg","type":"image\/jpeg"}],"author":"L.A. Louver","twitter_card":"summary_large_image","twitter_misc":{"Written by":"L.A. Louver"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#article","isPartOf":{"@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery"},"author":{"name":"L.A. Louver","@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158"},"headline":"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place","datePublished":"2013-11-29T18:01:13+00:00","dateModified":"2025-09-06T16:49:23+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery"},"wordCount":93,"commentCount":0,"image":{"@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage"},"thumbnailUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg","keywords":["installation","Joel Shapiro","l.a. louver","suspended work","wood"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery","url":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery","name":"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place - L.A. Louver - Journal","isPartOf":{"@id":"https:\/\/www.lalouver.com\/journal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage"},"image":{"@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage"},"thumbnailUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg","datePublished":"2013-11-29T18:01:13+00:00","dateModified":"2025-09-06T16:49:23+00:00","author":{"@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158"},"breadcrumb":{"@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#primaryimage","url":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg","contentUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2013\/11\/tumblr_mwwaqxE6jl1r7s5hko3_1280.jpg","width":1080,"height":720},{"@type":"BreadcrumbList","@id":"https:\/\/www.lalouver.com\/journal\/looking-for-post-thanksgiving-plans-the-gallery#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lalouver.com\/journal\/"},{"@type":"ListItem","position":2,"name":"A few snaps of Joel and crew skillfully situating the brilliant wooden forms in place"}]},{"@type":"WebSite","@id":"https:\/\/www.lalouver.com\/journal\/#website","url":"https:\/\/www.lalouver.com\/journal\/","name":"L.A. Louver - Journal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lalouver.com\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158","name":"L.A. Louver","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","caption":"L.A. Louver"},"sameAs":["https:\/\/www.lalouver.com\/journal"],"url":"https:\/\/www.lalouver.com\/journal\/author\/50percentopacity"}]}},"_links":{"self":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/1459","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/comments?post=1459"}],"version-history":[{"count":6,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/1459\/revisions"}],"predecessor-version":[{"id":6306,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/1459\/revisions\/6306"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/media\/1462"}],"wp:attachment":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/media?parent=1459"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/categories?post=1459"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/tags?post=1459"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}