{"id":1064,"date":"2014-10-08T01:06:23","date_gmt":"2014-10-08T01:06:23","guid":{"rendered":"https:\/\/www.lalouver.com\/journal\/index.php\/2014\/10\/08\/a-fully-illustrated-catalogue-on-sui-jianguo-was\/"},"modified":"2025-09-07T16:31:18","modified_gmt":"2025-09-07T16:31:18","slug":"a-fully-illustrated-catalogue-on-sui-jianguo-was","status":"publish","type":"post","link":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was","title":{"rendered":"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition"},"content":{"rendered":"\n<figure data-wp-context=\"{&quot;galleryId&quot;:&quot;6a57ee12dd05c&quot;}\" data-wp-interactive=\"core\/gallery\" class=\"wp-block-gallery has-nested-images columns-3 is-cropped wp-block-gallery-1 is-layout-flex wp-block-gallery-is-layout-flex\">\n<figure data-wp-context=\"{&quot;imageId&quot;:&quot;6a57ee12e0c65&quot;}\" data-wp-interactive=\"core\/image\" data-wp-key=\"6a57ee12e0c65\" class=\"wp-block-image size-large wp-lightbox-container\"><img loading=\"lazy\" decoding=\"async\" width=\"600\" height=\"394\" data-wp-class--hide=\"state.isContentHidden\" data-wp-class--show=\"state.isContentVisible\" data-wp-init=\"callbacks.setButtonStyles\" data-wp-on--click=\"actions.showLightbox\" data-wp-on--load=\"callbacks.setButtonStyles\" data-wp-on--pointerdown=\"actions.preloadImage\" data-wp-on--pointerenter=\"actions.preloadImageWithDelay\" data-wp-on--pointerleave=\"actions.cancelPreload\" data-wp-on-window--resize=\"callbacks.setButtonStyles\" data-id=\"1065\" src=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg\" alt=\"\" class=\"wp-image-1065\" srcset=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg 600w, https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640-300x197.jpg 300w\" sizes=\"auto, (max-width: 600px) 100vw, 600px\" \/><button\n\t\t\tclass=\"lightbox-trigger\"\n\t\t\ttype=\"button\"\n\t\t\taria-haspopup=\"dialog\"\n\t\t\tdata-wp-bind--aria-label=\"state.thisImage.triggerButtonAriaLabel\"\n\t\t\tdata-wp-init=\"callbacks.initTriggerButton\"\n\t\t\tdata-wp-on--click=\"actions.showLightbox\"\n\t\t\tdata-wp-style--right=\"state.thisImage.buttonRight\"\n\t\t\tdata-wp-style--top=\"state.thisImage.buttonTop\"\n\t\t>\n\t\t\t<svg xmlns=\"http:\/\/www.w3.org\/2000\/svg\" width=\"12\" height=\"12\" fill=\"none\" viewBox=\"0 0 12 12\">\n\t\t\t\t<path fill=\"#fff\" d=\"M2 0a2 2 0 0 0-2 2v2h1.5V2a.5.5 0 0 1 .5-.5h2V0H2Zm2 10.5H2a.5.5 0 0 1-.5-.5V8H0v2a2 2 0 0 0 2 2h2v-1.5ZM8 12v-1.5h2a.5.5 0 0 0 .5-.5V8H12v2a2 2 0 0 1-2 2H8Zm2-12a2 2 0 0 1 2 2v2h-1.5V2a.5.5 0 0 0-.5-.5H8V0h2Z\" \/>\n\t\t\t<\/svg>\n\t\t<\/button><\/figure>\n<\/figure>\n\n\n\n<p class=\"wp-block-paragraph\">A fully illustrated catalogue on <a href=\"http:\/\/lalouver.com\/html\/artist.cfm?tArtist_id=432\">Sui Jianguo<\/a> was produced in conjunction with our current exhibition of his work, on view at<a href=\"http:\/\/lalouver.com\/html\/exhibition.cfm?tExhibition_id=1036\"> L.A. Louver <\/a>through October 18, 2014. Featured in the catalogue is a comprehensive essay by art theorist and curator Su Lei, who follows the trajectory of Sui\u2019s career alongside China\u2019s recent history. The author also brings to focus Sui\u2019s relentless endeavors in addressing profound change in China\u2019s arts educational system.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">To read Su Lei\u2019s text, the complete catalogue can now be accessed online! <a href=\"http:\/\/www.lalouver.com\/suijianguo-catalogue\/\">Click here to be directed to the e-version.&nbsp;<\/a><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">IMAGE:&nbsp;Sui Jianguo,&nbsp;<em>Legacy Mantle<\/em>, 1997,&nbsp;Fiberglass,&nbsp;94.49 x 62.99 x 35.43 in. (240 x 160 x 90 cm) each<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition of his work, on view at L.A. Louver through October 18, 2014. Featured in the catalogue is a comprehensive essay by art theorist and curator Su Lei, who follows the trajectory of Sui\u2019s career alongside China\u2019s recent history. The author [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":1065,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"gallery","meta":{"footnotes":""},"categories":[1],"tags":[296,650,652,15,651,24,649,29],"class_list":["post-1064","post","type-post","status-publish","format-gallery","has-post-thumbnail","hentry","category-uncategorized","tag-catalogue","tag-essay","tag-jackets","tag-l-a-louver","tag-mao","tag-sculpture","tag-su-lei","tag-sui-jianguo","post_format-post-format-gallery"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v28.0 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\r\n<title>A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition - L.A. Louver - Journal<\/title>\r\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\r\n<link rel=\"canonical\" href=\"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was\" \/>\r\n<meta property=\"og:locale\" content=\"en_US\" \/>\r\n<meta property=\"og:type\" content=\"article\" \/>\r\n<meta property=\"og:title\" content=\"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition - L.A. Louver - Journal\" \/>\r\n<meta property=\"og:description\" content=\"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition of his work, on view at L.A. Louver through October 18, 2014. Featured in the catalogue is a comprehensive essay by art theorist and curator Su Lei, who follows the trajectory of Sui\u2019s career alongside China\u2019s recent history. The author [&hellip;]\" \/>\r\n<meta property=\"og:url\" content=\"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was\" \/>\r\n<meta property=\"og:site_name\" content=\"L.A. Louver - Journal\" \/>\r\n<meta property=\"article:published_time\" content=\"2014-10-08T01:06:23+00:00\" \/>\r\n<meta property=\"article:modified_time\" content=\"2025-09-07T16:31:18+00:00\" \/>\r\n<meta property=\"og:image\" content=\"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg\" \/>\r\n\t<meta property=\"og:image:width\" content=\"600\" \/>\r\n\t<meta property=\"og:image:height\" content=\"394\" \/>\r\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\r\n<meta name=\"author\" content=\"L.A. Louver\" \/>\r\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\r\n<meta name=\"twitter:label1\" content=\"Written by\" \/>\n\t<meta name=\"twitter:data1\" content=\"L.A. Louver\" \/>\n\t<meta name=\"twitter:label2\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data2\" content=\"1 minute\" \/>\r\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#article\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was\"},\"author\":{\"name\":\"L.A. Louver\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\"},\"headline\":\"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition\",\"datePublished\":\"2014-10-08T01:06:23+00:00\",\"dateModified\":\"2025-09-07T16:31:18+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was\"},\"wordCount\":129,\"commentCount\":0,\"image\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg\",\"keywords\":[\"catalogue\",\"essay\",\"jackets\",\"l.a. louver\",\"mao\",\"sculpture\",\"Su Lei\",\"sui jianguo\"],\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"CommentAction\",\"name\":\"Comment\",\"target\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#respond\"]}]},{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was\",\"name\":\"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition - L.A. Louver - Journal\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage\"},\"image\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage\"},\"thumbnailUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg\",\"datePublished\":\"2014-10-08T01:06:23+00:00\",\"dateModified\":\"2025-09-07T16:31:18+00:00\",\"author\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\"},\"breadcrumb\":{\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg\",\"contentUrl\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/wp-content\\\/uploads\\\/2014\\\/10\\\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg\",\"width\":600,\"height\":394},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/a-fully-illustrated-catalogue-on-sui-jianguo-was#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#website\",\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/\",\"name\":\"L.A. Louver - Journal\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"},{\"@type\":\"Person\",\"@id\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/#\\\/schema\\\/person\\\/d8960dc80ea751ac2c8a42ccc6f20158\",\"name\":\"L.A. Louver\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"en-US\",\"@id\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"url\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"contentUrl\":\"https:\\\/\\\/secure.gravatar.com\\\/avatar\\\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g\",\"caption\":\"L.A. Louver\"},\"sameAs\":[\"https:\\\/\\\/www.lalouver.com\\\/journal\"],\"url\":\"https:\\\/\\\/www.lalouver.com\\\/journal\\\/author\\\/50percentopacity\"}]}<\/script>\r\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition - L.A. Louver - Journal","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was","og_locale":"en_US","og_type":"article","og_title":"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition - L.A. Louver - Journal","og_description":"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition of his work, on view at L.A. Louver through October 18, 2014. Featured in the catalogue is a comprehensive essay by art theorist and curator Su Lei, who follows the trajectory of Sui\u2019s career alongside China\u2019s recent history. The author [&hellip;]","og_url":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was","og_site_name":"L.A. Louver - Journal","article_published_time":"2014-10-08T01:06:23+00:00","article_modified_time":"2025-09-07T16:31:18+00:00","og_image":[{"width":600,"height":394,"url":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg","type":"image\/jpeg"}],"author":"L.A. Louver","twitter_card":"summary_large_image","twitter_misc":{"Written by":"L.A. Louver","Est. reading time":"1 minute"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#article","isPartOf":{"@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was"},"author":{"name":"L.A. Louver","@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158"},"headline":"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition","datePublished":"2014-10-08T01:06:23+00:00","dateModified":"2025-09-07T16:31:18+00:00","mainEntityOfPage":{"@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was"},"wordCount":129,"commentCount":0,"image":{"@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage"},"thumbnailUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg","keywords":["catalogue","essay","jackets","l.a. louver","mao","sculpture","Su Lei","sui jianguo"],"inLanguage":"en-US","potentialAction":[{"@type":"CommentAction","name":"Comment","target":["https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#respond"]}]},{"@type":"WebPage","@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was","url":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was","name":"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition - L.A. Louver - Journal","isPartOf":{"@id":"https:\/\/www.lalouver.com\/journal\/#website"},"primaryImageOfPage":{"@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage"},"image":{"@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage"},"thumbnailUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg","datePublished":"2014-10-08T01:06:23+00:00","dateModified":"2025-09-07T16:31:18+00:00","author":{"@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158"},"breadcrumb":{"@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was"]}]},{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#primaryimage","url":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg","contentUrl":"https:\/\/www.lalouver.com\/journal\/wp-content\/uploads\/2014\/10\/tumblr_nd3pqnzSxP1r7s5hko1_640.jpg","width":600,"height":394},{"@type":"BreadcrumbList","@id":"https:\/\/www.lalouver.com\/journal\/a-fully-illustrated-catalogue-on-sui-jianguo-was#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/www.lalouver.com\/journal\/"},{"@type":"ListItem","position":2,"name":"A fully illustrated catalogue on Sui Jianguo was produced in conjunction with our current exhibition"}]},{"@type":"WebSite","@id":"https:\/\/www.lalouver.com\/journal\/#website","url":"https:\/\/www.lalouver.com\/journal\/","name":"L.A. Louver - Journal","description":"","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/www.lalouver.com\/journal\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"},{"@type":"Person","@id":"https:\/\/www.lalouver.com\/journal\/#\/schema\/person\/d8960dc80ea751ac2c8a42ccc6f20158","name":"L.A. Louver","image":{"@type":"ImageObject","inLanguage":"en-US","@id":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","url":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/5936e6d91a9a7d7ca0635878271b459c9ebc3b644f373409bee1dfce9cced46a?s=96&d=mm&r=g","caption":"L.A. Louver"},"sameAs":["https:\/\/www.lalouver.com\/journal"],"url":"https:\/\/www.lalouver.com\/journal\/author\/50percentopacity"}]}},"_links":{"self":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/1064","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/comments?post=1064"}],"version-history":[{"count":2,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/1064\/revisions"}],"predecessor-version":[{"id":6813,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/posts\/1064\/revisions\/6813"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/media\/1065"}],"wp:attachment":[{"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/media?parent=1064"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/categories?post=1064"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.lalouver.com\/journal\/wp-json\/wp\/v2\/tags?post=1064"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}